{"id":50021,"date":"2020-06-12T10:27:31","date_gmt":"2020-06-12T08:27:31","guid":{"rendered":"http:\/\/lownew.zadiasoftware.com\/product\/formacion-online-especial-mx\/"},"modified":"2026-09-02T07:03:11","modified_gmt":"2026-09-02T05:03:11","slug":"formacion-online-especial-mx","status":"publish","type":"product","link":"https:\/\/mx.lowpressurefitness.com\/en\/producto\/formacion-online-especial-mx\/","title":{"rendered":"Formaci\u00f3n Online Especial MX"},"content":{"rendered":"<p>IDIOMA: Espa\u00f1ol<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IDIOMA: Espa\u00f1ol<\/p>\n","protected":false},"featured_media":2043,"template":"","meta":[],"_links":{"self":[{"href":"https:\/\/mx.lowpressurefitness.com\/en\/wp-json\/wp\/v2\/product\/50021\/"}],"collection":[{"href":"https:\/\/mx.lowpressurefitness.com\/en\/wp-json\/wp\/v2\/product\/"}],"about":[{"href":"https:\/\/mx.lowpressurefitness.com\/en\/wp-json\/wp\/v2\/types\/product\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mx.lowpressurefitness.com\/en\/wp-json\/wp\/v2\/media\/2043\/"}],"wp:attachment":[{"href":"https:\/\/mx.lowpressurefitness.com\/en\/wp-json\/wp\/v2\/media\/?parent=50021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}