{"id":50469,"date":"2020-08-07T09:34:05","date_gmt":"2020-08-07T07:34:05","guid":{"rendered":"http:\/\/lownew.zadiasoftware.com\/product\/formacion-online-2\/"},"modified":"2026-09-01T13:49:43","modified_gmt":"2026-09-01T11:49:43","slug":"formacion-online-2","status":"publish","type":"product","link":"https:\/\/mx.lowpressurefitness.com\/es\/producto\/formacion-online-2\/","title":{"rendered":"Formaci\u00f3n Online MX"},"content":{"rendered":"<p>IDIOMA: Portugu\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IDIOMA: Portugu\u00e9s<\/p>\n","protected":false},"featured_media":2043,"template":"","meta":[],"_links":{"self":[{"href":"https:\/\/mx.lowpressurefitness.com\/es\/wp-json\/wp\/v2\/product\/50469\/"}],"collection":[{"href":"https:\/\/mx.lowpressurefitness.com\/es\/wp-json\/wp\/v2\/product\/"}],"about":[{"href":"https:\/\/mx.lowpressurefitness.com\/es\/wp-json\/wp\/v2\/types\/product\/"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mx.lowpressurefitness.com\/es\/wp-json\/wp\/v2\/media\/2043\/"}],"wp:attachment":[{"href":"https:\/\/mx.lowpressurefitness.com\/es\/wp-json\/wp\/v2\/media\/?parent=50469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}